{"id":124,"count":1,"description":"","link":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/","name":"Escalade europ\u00e9enne","slug":"escalade-europeenne","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Explorateurs Catalans\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/\",\"url\":\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/\",\"name\":\"Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans\",\"isPartOf\":{\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lesexplorateurscatalans.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escalade europ\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#website\",\"url\":\"https:\/\/lesexplorateurscatalans.fr\/\",\"name\":\"Les Explorateurs Catalans\",\"description\":\"Les Explorateurs Catalans : Votre boussole pour l&#039;aventure.\",\"publisher\":{\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#organization\"},\"alternateName\":\"LEC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lesexplorateurscatalans.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#organization\",\"name\":\"Les Explorateurs Catalans\",\"alternateName\":\"LEC\",\"url\":\"https:\/\/lesexplorateurscatalans.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png\",\"contentUrl\":\"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png\",\"width\":500,\"height\":500,\"caption\":\"Les Explorateurs Catalans\"},\"image\":{\"@id\":\"https:\/\/lesexplorateurscatalans.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lesexplorateurscatalans\",\"https:\/\/www.relive.cc\/profile\/niko660\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans","og_url":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/","og_site_name":"Les Explorateurs Catalans","og_image":[{"width":500,"height":500,"url":"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/","url":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/","name":"Archives des Escalade europ\u00e9enne - Les Explorateurs Catalans","isPartOf":{"@id":"https:\/\/lesexplorateurscatalans.fr\/#website"},"breadcrumb":{"@id":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/lesexplorateurscatalans.fr\/index.php\/tag\/escalade-europeenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesexplorateurscatalans.fr\/"},{"@type":"ListItem","position":2,"name":"Escalade europ\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/lesexplorateurscatalans.fr\/#website","url":"https:\/\/lesexplorateurscatalans.fr\/","name":"Les Explorateurs Catalans","description":"Les Explorateurs Catalans : Votre boussole pour l&#039;aventure.","publisher":{"@id":"https:\/\/lesexplorateurscatalans.fr\/#organization"},"alternateName":"LEC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesexplorateurscatalans.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lesexplorateurscatalans.fr\/#organization","name":"Les Explorateurs Catalans","alternateName":"LEC","url":"https:\/\/lesexplorateurscatalans.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lesexplorateurscatalans.fr\/#\/schema\/logo\/image\/","url":"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png","contentUrl":"https:\/\/lesexplorateurscatalans.fr\/wp-content\/uploads\/2024\/04\/DALL_E-2024-02-19-13.15-removebg-preview.png","width":500,"height":500,"caption":"Les Explorateurs Catalans"},"image":{"@id":"https:\/\/lesexplorateurscatalans.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lesexplorateurscatalans","https:\/\/www.relive.cc\/profile\/niko660"]}]}},"_links":{"self":[{"href":"https:\/\/lesexplorateurscatalans.fr\/index.php\/wp-json\/wp\/v2\/tags\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesexplorateurscatalans.fr\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lesexplorateurscatalans.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lesexplorateurscatalans.fr\/index.php\/wp-json\/wp\/v2\/posts?tags=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}